{"id":5045,"date":"2025-10-13T16:25:38","date_gmt":"2025-10-13T14:25:38","guid":{"rendered":"https:\/\/rutadelvinovaldeorras.com\/socios\/bodegas-blare\/"},"modified":"2025-10-13T16:25:38","modified_gmt":"2025-10-13T14:25:38","slug":"bodegas-blare","status":"publish","type":"socios","link":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/","title":{"rendered":"Bodegas Blare"},"excerpt":{"rendered":"","protected":false},"featured_media":5044,"template":"","localizacion-socio":[21],"categoria-socio":[13],"class_list":["post-5045","socios","type-socios","status-publish","has-post-thumbnail","hentry","localizacion-socio-o-barco-de-valdeorras","categoria-socio-bodegas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bodegas Blare | Vi\u00f1os ecol\u00f3xicos en Valdeorras<\/title>\n<meta name=\"description\" content=\"Bodegas Blare elabora vinos ecol\u00f3gicos en Valdeorras con respeto al territorio, el vi\u00f1edo y los ritmos naturales de la tierra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bodegas Blare | Vi\u00f1os ecol\u00f3xicos en Valdeorras\" \/>\n<meta property=\"og:description\" content=\"Bodegas Blare elabora vinos ecol\u00f3gicos en Valdeorras con respeto al territorio, el vi\u00f1edo y los ritmos naturales de la tierra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ruta del Vino Valdeorras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RutadelVinoValdeorras\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/552179079_17870028039441155_5538615254230115332_n.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"914\" \/>\n\t<meta property=\"og:image:height\" content=\"1214\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/\",\"name\":\"Bodegas Blare | Vi\u00f1os ecol\u00f3xicos en Valdeorras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/552179079_17870028039441155_5538615254230115332_n.webp\",\"datePublished\":\"2025-10-13T14:25:38+00:00\",\"description\":\"Bodegas Blare elabora vinos ecol\u00f3gicos en Valdeorras con respeto al territorio, el vi\u00f1edo y los ritmos naturales de la tierra.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/552179079_17870028039441155_5538615254230115332_n.webp\",\"contentUrl\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/552179079_17870028039441155_5538615254230115332_n.webp\",\"width\":914,\"height\":1214,\"caption\":\"Bodegas Blare vi\u00f1os ecol\u00f3xicos en Valdeorras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/socios\\\/bodegas-blare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bodegas Blare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#website\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/\",\"name\":\"Ruta del Vino Valdeorras\",\"description\":\"La Ruta del Vino de Valdeorras es un recorrido que nos transporta a trav\u00e9s de la historia y la cultura vin\u00edcola de una de las comarcas m\u00e1s singulares de Galicia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#organization\",\"name\":\"Ruta del Vino Valdeorras\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/valdeoras-color.svg\",\"contentUrl\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/valdeoras-color.svg\",\"width\":884,\"height\":131,\"caption\":\"Ruta del Vino Valdeorras\"},\"image\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RutadelVinoValdeorras\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ruta_vino_valdeorras\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bodegas Blare | Vi\u00f1os ecol\u00f3xicos en Valdeorras","description":"Bodegas Blare elabora vinos ecol\u00f3gicos en Valdeorras con respeto al territorio, el vi\u00f1edo y los ritmos naturales de la tierra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/","og_locale":"gl_ES","og_type":"article","og_title":"Bodegas Blare | Vi\u00f1os ecol\u00f3xicos en Valdeorras","og_description":"Bodegas Blare elabora vinos ecol\u00f3gicos en Valdeorras con respeto al territorio, el vi\u00f1edo y los ritmos naturales de la tierra.","og_url":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/","og_site_name":"Ruta del Vino Valdeorras","article_publisher":"https:\/\/www.facebook.com\/RutadelVinoValdeorras\/","og_image":[{"width":914,"height":1214,"url":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/552179079_17870028039441155_5538615254230115332_n.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/","url":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/","name":"Bodegas Blare | Vi\u00f1os ecol\u00f3xicos en Valdeorras","isPartOf":{"@id":"https:\/\/rutadelvinovaldeorras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/#primaryimage"},"image":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/#primaryimage"},"thumbnailUrl":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/552179079_17870028039441155_5538615254230115332_n.webp","datePublished":"2025-10-13T14:25:38+00:00","description":"Bodegas Blare elabora vinos ecol\u00f3gicos en Valdeorras con respeto al territorio, el vi\u00f1edo y los ritmos naturales de la tierra.","breadcrumb":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/#primaryimage","url":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/552179079_17870028039441155_5538615254230115332_n.webp","contentUrl":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/552179079_17870028039441155_5538615254230115332_n.webp","width":914,"height":1214,"caption":"Bodegas Blare vi\u00f1os ecol\u00f3xicos en Valdeorras"},{"@type":"BreadcrumbList","@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/socios\/bodegas-blare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rutadelvinovaldeorras.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Bodegas Blare"}]},{"@type":"WebSite","@id":"https:\/\/rutadelvinovaldeorras.com\/#website","url":"https:\/\/rutadelvinovaldeorras.com\/","name":"Ruta del Vino Valdeorras","description":"La Ruta del Vino de Valdeorras es un recorrido que nos transporta a trav\u00e9s de la historia y la cultura vin\u00edcola de una de las comarcas m\u00e1s singulares de Galicia.","publisher":{"@id":"https:\/\/rutadelvinovaldeorras.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rutadelvinovaldeorras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/rutadelvinovaldeorras.com\/#organization","name":"Ruta del Vino Valdeorras","url":"https:\/\/rutadelvinovaldeorras.com\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/rutadelvinovaldeorras.com\/#\/schema\/logo\/image\/","url":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/06\/valdeoras-color.svg","contentUrl":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/06\/valdeoras-color.svg","width":884,"height":131,"caption":"Ruta del Vino Valdeorras"},"image":{"@id":"https:\/\/rutadelvinovaldeorras.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RutadelVinoValdeorras\/","https:\/\/www.instagram.com\/ruta_vino_valdeorras\/"]}]}},"_links":{"self":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/socios\/5045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/socios"}],"about":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/types\/socios"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/media\/5044"}],"wp:attachment":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/media?parent=5045"}],"wp:term":[{"taxonomy":"localizacion-socio","embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/localizacion-socio?post=5045"},{"taxonomy":"categoria-socio","embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/categoria-socio?post=5045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}