{"id":4951,"date":"2025-06-09T10:03:37","date_gmt":"2025-06-09T08:03:37","guid":{"rendered":"https:\/\/rutadelvinovaldeorras.com\/festival-entre-covas\/"},"modified":"2025-06-09T10:03:37","modified_gmt":"2025-06-09T08:03:37","slug":"festival-entre-covas","status":"publish","type":"post","link":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/","title":{"rendered":"Festival &#8220;Entre Covas&#8221;"},"content":{"rendered":"<p>O <strong data-start=\"1698\" data-end=\"1733\">Festival Entre Covas Valdeorras<\/strong> \u00e9 unha proposta cultural da Ruta do Vi\u00f1o de Valdeorras que pon en valor as covas como patrimonio \u00fanico a trav\u00e9s de experiencias enogastron\u00f3micas e artes esc\u00e9nicas.<\/p>\n<p>Estes actos culturais ser\u00e1n: un espect\u00e1culo de maxia, un concerto de m\u00fasica tradicional oral galega, e a representaci\u00f3n dunha peza de danza contempor\u00e1nea que se celebrar\u00e1n durante tres venres nos meses de xu\u00f1o, xullo e agosto.<\/p>\n<h2><strong>Alcance da proposta<\/strong><\/h2>\n<p>O festival \u201cENTRE COVAS\u201d materializarase a trav\u00e9s da celebraci\u00f3n de tres experiencias enogastron\u00f3micas nas covas. Tr\u00e1tase de encontros destinados a dar a co\u00f1ecer o principal recurso patrimonial que ten a Asociaci\u00f3n da Ruta do Vi\u00f1o Valdeorras, que son as covas, d\u00e1ndolles un uso diferente ao habitual. Cada un destes encontros ter\u00e1 como obxectivo po\u00f1er en valor diferentes artes esc\u00e9nicas.  <\/p>\n<p>Cada un destes eventos ten un aforo limitado a 50 persoas debido \u00e1 reducida capacidade destes espazos. O primeiro dos eventos ter\u00e1 lugar na Cova da Xabreira, no entorno das covas de Seadur, o d\u00eda 20 de xu\u00f1o \u00e1s 20:00 h. O segundo dos eventos celebrarase en As Pinguelas, combinando tres covas de adegas asociadas. Recibirase aos asistentes en Melillas cun vi\u00f1o e visita \u00e1 cova, para posteriormente realizar o concerto en Joaqu\u00edn Rebolledo e rematar diante de Alan coa degustaci\u00f3n de vi\u00f1os e pinchos. Este evento ter\u00e1 lugar o d\u00eda 18 de xullo \u00e1s 20:00 h. O \u00faltimo dos eventos ser\u00e1 na Bodega Blare no concello do Barco o d\u00eda 19 de setembro \u00e1s 20:00 h.     <\/p>\n<p>Os artistas escollidos para levar a cabo cada unha das propostas son os seguintes:<\/p>\n<p><em><strong>1.- Espect\u00e1culo de maxia 20 de xu\u00f1o en Seadur \u00e1s 20:00 h (Cova da Xabreira) <\/strong><\/em><\/p>\n<p><strong>Joshua Kenneth<\/strong><\/p>\n<p><strong>DEGUSTACI\u00d3N DE IMPOSIBLES<\/strong><\/p>\n<p>Degustaci\u00f3n de imposibles \u00e9 unha obra apta para todos os p\u00fablicos creada polo ilusionista guiri-galego Joshua Kenneth. Nesta selecci\u00f3n de imposibles que se fan realidade, a percepci\u00f3n do p\u00fablico dist\u00f3rcese con impactantes elementos visuais e po\u00e9ticos como post-it de xab\u00f3n, paos de seda ou sombras chinesas. Setenta minutos de asombro, humor e misterio mesturados cun pouco da historia do ilusionismo. Unha experiencia interactiva, divertida e art\u00edstica que invita ao p\u00fablico a entrar nun mundo onde todo pode transformarse e nada \u00e9 imposible. Este formato de Joshua Kenneth \u00e9 maxia de preto, perfectamente adaptable a espazos pequenos, un espect\u00e1culo personalizado no que Joshua crea momentos de maxia nos que a Ruta do Vi\u00f1o e as Covas poden ser protagonistas, empregando unha imaxe, o propio nome ou o que se considere de interese.    <\/p>\n<p><em><strong>2.- Concerto de m\u00fasica tradicional oral galega 18 de xullo en A R\u00faa \u00e1s 20:00 h (Covas de Adega Melillas, Joaqu\u00edn Rebolledo e Alan de Val) <\/strong><\/em><\/p>\n<p><strong>Carmela<\/strong><\/p>\n<p><strong>M\u00daSICA | Tradicional<\/strong><\/p>\n<p><strong> <\/strong>Carmela \u00e9 un proxecto musical que basa o seu repertorio na tradici\u00f3n oral galega, a trav\u00e9s do canto e da percusi\u00f3n manual como elementos definitorios. Iniciando o traballo desde informantes e arquivos musicais, o obxectivo do proxecto \u00e9 trasladar aos escenarios a esencia destas melod\u00edas acompa\u00f1adas dunha visi\u00f3n propia e actual, empregando non s\u00f3 criterios est\u00e9ticos, sen\u00f3n tam\u00e9n outros vinculados \u00e1 an\u00e1lise musical e ao contexto da m\u00fasica coa que se traballa, un achegamento que suma a investigaci\u00f3n etnomusicol\u00f3xica coa interpretaci\u00f3n e arranxo musical. Carmela utiliza a tradici\u00f3n como unha entidade flexible e pl\u00e1stica que se adapta ao contexto musical actual a trav\u00e9s de sons que van desde percusi\u00f3ns ata referencias electr\u00f3nicas. Un proxecto diferente no seu discurso tanto musical como extramusical que sit\u00faa a tradici\u00f3n oral e a perspectiva de x\u00e9nero no centro.   <\/p>\n<p>Carmela \u00e9 a visi\u00f3n musical da tradici\u00f3n oral de Carme L\u00f3pez, un proxecto que naceu en 2022 sub\u00edndose aos escenarios con diferentes propostas esc\u00e9nicas, e que en novembro de 2024 lanzou o seu primeiro \u00e1lbum: Venid todas (editado co selo Microscopi). A presentaci\u00f3n deste disco constar\u00e1 dun directo en formato tr\u00edo. <\/p>\n<p><em><strong> 3.- Representaci\u00f3n dunha peza de danza contempor\u00e1nea 19 de setembro en Vilanova \u00e1s 20:00 h (Cova de Bodegas Blare) <\/strong><\/em><\/p>\n<p><strong>Fran Sieira<\/strong><\/p>\n<p><strong>UN BAILE CEIBE<\/strong><\/p>\n<p><strong>DANZA<\/strong><\/p>\n<p>Tras o \u00e9xito de Demente, Fran Sieira Compa\u00f1\u00eda de Danza presenta CEIBE, unha peza contempor\u00e1nea reflexo da danza e m\u00fasica tradicional que investiga a relaci\u00f3n entre o x\u00e9nero e a nosa tradici\u00f3n. Ceibe afonda en como o x\u00e9nero est\u00e1 presente en diferentes \u00e1mbitos, inclu\u00edndo unha manifestaci\u00f3n cultural tan importante como a danza tradicional. <\/p>\n<p>Ceibe busca entender que \u00e9 o x\u00e9nero para n\u00f3s como individuos, como colectivo e tam\u00e9n como sociedade. Reflexiona sobre as categor\u00edas de x\u00e9nero e os estereotipos socialmente impostos para distanciarse da normatividade e arrastrala cara \u00e1s marxes, desde onde se constr\u00faen novas formas de entender o corpo e o movemento. <\/p>\n<p>En cada un destes eventos, ademais do espect\u00e1culo, os asistentes poder\u00e1n desfrutar de tres vi\u00f1os das seis referencias dispo\u00f1ibles das adegas asociadas \u00e1 Ruta do Vi\u00f1o, e de pinchos fr\u00edos servidos por Cova da Xabreira, Paladium e Pazo del Castro, inclu\u00eddos no prezo da entrada. O custo da entrada por espect\u00e1culo \u00e9 de 25 \u20ac. Aqueles que desexen asistir aos tres espect\u00e1culos poder\u00e1n adquirir un bono con un custo de 60 \u20ac.  <\/p>\n<p>As entradas p\u00f3dense adquirir na tenda de m\u00fasica Tono e Son en O Barco ou a trav\u00e9s do seguinte <a href=\"https:\/\/forms.gle\/U2bb9jafBW9cxMwq6\"><strong>FORMULARIO<\/strong><\/a><\/p>\n<p>Ademais, os asistentes ao festival desfrutar\u00e1n de condici\u00f3ns especiais nos aloxamentos Rectoral de Seadur, Pacio do Sil e Pazo del Castro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Festival Entre Covas Valdeorras \u00e9 unha proposta cultural da Ruta do Vi\u00f1o de Valdeorras que pon en valor as covas como patrimonio \u00fanico a trav\u00e9s de experiencias enogastron\u00f3micas e artes esc\u00e9nicas. Estes actos culturais ser\u00e1n: un espect\u00e1culo de maxia, un concerto de m\u00fasica tradicional oral galega, e a representaci\u00f3n dunha peza de danza contempor\u00e1nea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-4951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sen-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entre Covas Valdeorras: cultura e vi\u00f1o nas covas<\/title>\n<meta name=\"description\" content=\"Descobre o Festival Entre Covas Valdeorras, unha proposta cultural e enotur\u00edstica en covas tradicionais con vi\u00f1o e gastronom\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entre Covas Valdeorras: cultura e vi\u00f1o nas covas\" \/>\n<meta property=\"og:description\" content=\"Descobre o Festival Entre Covas Valdeorras, unha proposta cultural e enotur\u00edstica en covas tradicionais con vi\u00f1o e gastronom\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/\" \/>\n<meta property=\"og:site_name\" content=\"Ruta del Vino Valdeorras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RutadelVinoValdeorras\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T08:03:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/Uva-Valdeorras-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1756\" \/>\n\t<meta property=\"og:image:height\" content=\"1165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Adm-RuDlVNo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adm-RuDlVNo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/\"},\"author\":{\"name\":\"Adm-RuDlVNo\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#\\\/schema\\\/person\\\/560310151105d9ff874d7bd598d53179\"},\"headline\":\"Festival &#8220;Entre Covas&#8221;\",\"datePublished\":\"2025-06-09T08:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/\"},\"wordCount\":947,\"publisher\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uva-Valdeorras-9.webp\",\"articleSection\":[\"Sen categor\u00eda\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/\",\"name\":\"Entre Covas Valdeorras: cultura e vi\u00f1o nas covas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uva-Valdeorras-9.webp\",\"datePublished\":\"2025-06-09T08:03:37+00:00\",\"description\":\"Descobre o Festival Entre Covas Valdeorras, unha proposta cultural e enotur\u00edstica en covas tradicionais con vi\u00f1o e gastronom\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uva-Valdeorras-9.webp\",\"contentUrl\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Uva-Valdeorras-9.webp\",\"width\":1756,\"height\":1165,\"caption\":\"Festival Entre Covas Valdeorras nas covas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/festival-entre-covas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival &#8220;Entre Covas&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#website\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/\",\"name\":\"Ruta del Vino Valdeorras\",\"description\":\"La Ruta del Vino de Valdeorras es un recorrido que nos transporta a trav\u00e9s de la historia y la cultura vin\u00edcola de una de las comarcas m\u00e1s singulares de Galicia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#organization\",\"name\":\"Ruta del Vino Valdeorras\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/valdeoras-color.svg\",\"contentUrl\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/valdeoras-color.svg\",\"width\":884,\"height\":131,\"caption\":\"Ruta del Vino Valdeorras\"},\"image\":{\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RutadelVinoValdeorras\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ruta_vino_valdeorras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rutadelvinovaldeorras.com\\\/#\\\/schema\\\/person\\\/560310151105d9ff874d7bd598d53179\",\"name\":\"Adm-RuDlVNo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c29ab891d021b6606086070500989afef5fc6a76383cb0dc009e03a484613217?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c29ab891d021b6606086070500989afef5fc6a76383cb0dc009e03a484613217?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c29ab891d021b6606086070500989afef5fc6a76383cb0dc009e03a484613217?s=96&d=mm&r=g\",\"caption\":\"Adm-RuDlVNo\"},\"sameAs\":[\"https:\\\/\\\/rutadelvinovaldeorras.eosaweb.com\"],\"url\":\"#\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entre Covas Valdeorras: cultura e vi\u00f1o nas covas","description":"Descobre o Festival Entre Covas Valdeorras, unha proposta cultural e enotur\u00edstica en covas tradicionais con vi\u00f1o e gastronom\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/","og_locale":"gl_ES","og_type":"article","og_title":"Entre Covas Valdeorras: cultura e vi\u00f1o nas covas","og_description":"Descobre o Festival Entre Covas Valdeorras, unha proposta cultural e enotur\u00edstica en covas tradicionais con vi\u00f1o e gastronom\u00eda.","og_url":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/","og_site_name":"Ruta del Vino Valdeorras","article_publisher":"https:\/\/www.facebook.com\/RutadelVinoValdeorras\/","article_published_time":"2025-06-09T08:03:37+00:00","og_image":[{"width":1756,"height":1165,"url":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/Uva-Valdeorras-9.webp","type":"image\/webp"}],"author":"Adm-RuDlVNo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Adm-RuDlVNo","Tempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/#article","isPartOf":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/"},"author":{"name":"Adm-RuDlVNo","@id":"https:\/\/rutadelvinovaldeorras.com\/#\/schema\/person\/560310151105d9ff874d7bd598d53179"},"headline":"Festival &#8220;Entre Covas&#8221;","datePublished":"2025-06-09T08:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/"},"wordCount":947,"publisher":{"@id":"https:\/\/rutadelvinovaldeorras.com\/#organization"},"image":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/#primaryimage"},"thumbnailUrl":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/Uva-Valdeorras-9.webp","articleSection":["Sen categor\u00eda"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/","url":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/","name":"Entre Covas Valdeorras: cultura e vi\u00f1o nas covas","isPartOf":{"@id":"https:\/\/rutadelvinovaldeorras.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/#primaryimage"},"image":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/#primaryimage"},"thumbnailUrl":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/Uva-Valdeorras-9.webp","datePublished":"2025-06-09T08:03:37+00:00","description":"Descobre o Festival Entre Covas Valdeorras, unha proposta cultural e enotur\u00edstica en covas tradicionais con vi\u00f1o e gastronom\u00eda.","breadcrumb":{"@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/#primaryimage","url":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/Uva-Valdeorras-9.webp","contentUrl":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/10\/Uva-Valdeorras-9.webp","width":1756,"height":1165,"caption":"Festival Entre Covas Valdeorras nas covas"},{"@type":"BreadcrumbList","@id":"https:\/\/rutadelvinovaldeorras.com\/gl\/festival-entre-covas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rutadelvinovaldeorras.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Festival &#8220;Entre Covas&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/rutadelvinovaldeorras.com\/#website","url":"https:\/\/rutadelvinovaldeorras.com\/","name":"Ruta del Vino Valdeorras","description":"La Ruta del Vino de Valdeorras es un recorrido que nos transporta a trav\u00e9s de la historia y la cultura vin\u00edcola de una de las comarcas m\u00e1s singulares de Galicia.","publisher":{"@id":"https:\/\/rutadelvinovaldeorras.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rutadelvinovaldeorras.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/rutadelvinovaldeorras.com\/#organization","name":"Ruta del Vino Valdeorras","url":"https:\/\/rutadelvinovaldeorras.com\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/rutadelvinovaldeorras.com\/#\/schema\/logo\/image\/","url":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/06\/valdeoras-color.svg","contentUrl":"https:\/\/rutadelvinovaldeorras.com\/wp-content\/uploads\/2025\/06\/valdeoras-color.svg","width":884,"height":131,"caption":"Ruta del Vino Valdeorras"},"image":{"@id":"https:\/\/rutadelvinovaldeorras.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RutadelVinoValdeorras\/","https:\/\/www.instagram.com\/ruta_vino_valdeorras\/"]},{"@type":"Person","@id":"https:\/\/rutadelvinovaldeorras.com\/#\/schema\/person\/560310151105d9ff874d7bd598d53179","name":"Adm-RuDlVNo","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/c29ab891d021b6606086070500989afef5fc6a76383cb0dc009e03a484613217?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c29ab891d021b6606086070500989afef5fc6a76383cb0dc009e03a484613217?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c29ab891d021b6606086070500989afef5fc6a76383cb0dc009e03a484613217?s=96&d=mm&r=g","caption":"Adm-RuDlVNo"},"sameAs":["https:\/\/rutadelvinovaldeorras.eosaweb.com"],"url":"#"}]}},"_links":{"self":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/posts\/4951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/comments?post=4951"}],"version-history":[{"count":0,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/posts\/4951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/media\/4950"}],"wp:attachment":[{"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/media?parent=4951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/categories?post=4951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rutadelvinovaldeorras.com\/gl\/wp-json\/wp\/v2\/tags?post=4951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}